{"id":760,"date":"2022-01-18T20:40:54","date_gmt":"2022-01-18T20:40:54","guid":{"rendered":"https:\/\/heritageclub.ca\/kebec\/?p=760"},"modified":"2022-01-18T20:40:54","modified_gmt":"2022-01-18T20:40:54","slug":"2-dons-de-500-a-des-organisations-prenant-soin-de-personnes-handicapees","status":"publish","type":"post","link":"https:\/\/heritageclub.ca\/kebec\/2022\/01\/18\/2-dons-de-500-a-des-organisations-prenant-soin-de-personnes-handicapees\/","title":{"rendered":"2 dons de $500 \u00e0 des organisations prenant soin de personnes Handicap\u00e9es"},"content":{"rendered":"<p>Le 15 juillet et le 21 juillet, notre chapitre a r\u00e9pondu aux demandes de financement de la Corporation des jeunes handicap\u00e9s de Charlesbourg et de l\u2019organisme communautaire Laura L\u00e9merveil.<\/p>\n<p>Un ch\u00e8que de $500 a \u00e9t\u00e9 remis lors de la pr\u00e9sentation d\u2019un spectacle de marionnette \u00e0 la corporation des jeunes handicap\u00e9s de Charlesbourg le 15 juillet en pr\u00e9sence de Mme Marie-Laurence Gauthier, coordonatrice, Anne-Marie Cardin (AnneMarionette), Bernard Desrochers, secr\u00e9taire-tr\u00e9sorier du club H\u00e9ritage K\u00e9bec et Marc Jacob, pr\u00e9sident int\u00e9rimaire du club H\u00e9ritage K\u00e9bec. Le don a permis \u00e0 la corporation de payer cet \u00e9v\u00e9nement.<\/p>\n<p>Ci-bas quelques photos prises lors de l\u2019\u00e9v\u00e9nement.<br \/>\n<a href=\"https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2022\/01\/theatre-en-action.jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2022\/01\/theatre-en-action.jpeg\" alt=\"\" width=\"640\" height=\"480\" class=\"alignnone size-full wp-image-761\" srcset=\"https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2022\/01\/theatre-en-action.jpeg 640w, https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2022\/01\/theatre-en-action-300x225.jpeg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<a href=\"https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2022\/01\/Remise-cheque-JHC.jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2022\/01\/Remise-cheque-JHC.jpeg\" alt=\"\" width=\"640\" height=\"480\" class=\"alignnone size-full wp-image-765\" srcset=\"https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2022\/01\/Remise-cheque-JHC.jpeg 640w, https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2022\/01\/Remise-cheque-JHC-300x225.jpeg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n<a href=\"https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2022\/01\/Anne-marionette-theatre-1024x768-1.jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2022\/01\/Anne-marionette-theatre-1024x768-1.jpeg\" alt=\"\" width=\"1024\" height=\"768\" class=\"alignnone size-full wp-image-767\" srcset=\"https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2022\/01\/Anne-marionette-theatre-1024x768-1.jpeg 1024w, https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2022\/01\/Anne-marionette-theatre-1024x768-1-300x225.jpeg 300w, https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2022\/01\/Anne-marionette-theatre-1024x768-1-768x576.jpeg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n<p>AnneMarionnette en action<br \/>\nVous pouvez obtenir plus d\u2019information sur la corporation \u00e0 www.jeuneshandicapesdecharlesbourg.com ainsi que AnneMarionnette sur sa page facebook annemarionnette.<\/p>\n<p>\u00c9galement, le 21 juillet, dans nos locaux nous avons remis un ch\u00e8que de $500 \u00e0 l\u2019organisme communautaire Laura L\u00e9merveil en pr\u00e9sence de Mme Francine Dor\u00e9e, Directrice du financement et des partenariats pour l\u2019organisme, Victor Boudreault et sa fille Annie-Claude qui sont impliqu\u00e9s activement dans l\u2019organisme depuis plusieurs ann\u00e9es, Bernard Desrochers et Marc Jacob du club H\u00e9ritage K\u00e9bec. Vous pouvez obtenir toute l\u2019information \u00e0 propos de l\u2019organisme \u00e0 Lauralemerveil.ca<\/p>\n<p>Ci bas une photo de la remise du ch\u00e8que.<\/p>\n<a href=\"https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2022\/01\/Remise-cheque-Laura-Lemerveil-1.jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2022\/01\/Remise-cheque-Laura-Lemerveil-1.jpeg\" alt=\"\" width=\"640\" height=\"480\" class=\"alignnone size-full wp-image-763\" srcset=\"https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2022\/01\/Remise-cheque-Laura-Lemerveil-1.jpeg 640w, https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2022\/01\/Remise-cheque-Laura-Lemerveil-1-300x225.jpeg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n","protected":false},"excerpt":{"rendered":"<p>Le 15 juillet et le 21 juillet, notre chapitre a r\u00e9pondu aux demandes de financement de la Corporation des jeunes handicap\u00e9s de Charlesbourg et de l\u2019organisme communautaire Laura L\u00e9merveil. Un ch\u00e8que de $500 a \u00e9t\u00e9 remis lors de la pr\u00e9sentation d\u2019un spectacle de marionnette \u00e0 la corporation des jeunes handicap\u00e9s de Charlesbourg le 15 juillet&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/heritageclub.ca\/kebec\/2022\/01\/18\/2-dons-de-500-a-des-organisations-prenant-soin-de-personnes-handicapees\/\" title=\"Read 2 dons de $500 \u00e0 des organisations prenant soin de personnes Handicap\u00e9es\">Lire la suite &raquo;<\/a><\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-760","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/heritageclub.ca\/kebec\/wp-json\/wp\/v2\/posts\/760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/heritageclub.ca\/kebec\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/heritageclub.ca\/kebec\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/heritageclub.ca\/kebec\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/heritageclub.ca\/kebec\/wp-json\/wp\/v2\/comments?post=760"}],"version-history":[{"count":1,"href":"https:\/\/heritageclub.ca\/kebec\/wp-json\/wp\/v2\/posts\/760\/revisions"}],"predecessor-version":[{"id":769,"href":"https:\/\/heritageclub.ca\/kebec\/wp-json\/wp\/v2\/posts\/760\/revisions\/769"}],"wp:attachment":[{"href":"https:\/\/heritageclub.ca\/kebec\/wp-json\/wp\/v2\/media?parent=760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/heritageclub.ca\/kebec\/wp-json\/wp\/v2\/categories?post=760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/heritageclub.ca\/kebec\/wp-json\/wp\/v2\/tags?post=760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}