{"id":1099,"date":"2024-03-16T19:03:10","date_gmt":"2024-03-16T19:03:10","guid":{"rendered":"https:\/\/heritageclub.ca\/kebec\/?p=1099"},"modified":"2024-03-16T19:03:10","modified_gmt":"2024-03-16T19:03:10","slug":"don-de-500-a-lorganisme-laura-lemerveil","status":"publish","type":"post","link":"https:\/\/heritageclub.ca\/kebec\/2024\/03\/16\/don-de-500-a-lorganisme-laura-lemerveil\/","title":{"rendered":"Don de $500 \u00e0 l&rsquo;organisme Laura L\u00e9merveil"},"content":{"rendered":"<p>Suite \u00e0 une demande d\u2019appui financier, c\u2019est avec plaisir que le pr\u00e9sident Marc Jacob est all\u00e9 pr\u00e9senter un ch\u00e8que \u00a0de $500 \u00e0 Madame Martine Thibault, Directrice du d\u00e9veloppement philanthropique chez Laura L\u00e9merveil.<\/p>\n<p>La pr\u00e9sentation a eu lieu \u00e0 la <strong>Maison Famille Suzanne Leclerc<\/strong> le 13 mars dernier.<\/p>\n<p>Voici la raison d\u2019\u00eatre de cet organisme exceptionnel\u00a0:<\/p>\n<p>L\u2019organisme communautaire Laura L\u00e9merveil ose croire qu\u2019il est possible de s\u2019accomplir pleinement malgr\u00e9 la s\u00e9v\u00e9rit\u00e9 du polyhandicap.<\/p>\n<p>Sensible et \u00e0 l\u2019\u00e9coute des besoins exprim\u00e9s par les familles et leurs enfants vivant en situation de handicaps multiples et s\u00e9v\u00e8res, il les soutient et les accompagne en d\u00e9veloppant un continuum de services de proximit\u00e9 normalisant.<\/p>\n<p>Leur slogan : Plein le coeur, plein les sens.<\/p>\n<p>Plus de d\u00e9tails sur leur site Web \u00e0 <a href=\"https:\/\/lauralemerveil.ca\/\">https:\/\/lauralemerveil.ca\/<\/a><\/p>\n<p>Ci-bas quelque photos.<\/p>\n<p>Affiche \u00e0 l&rsquo;accueil<\/p>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1092\" src=\"https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2024\/03\/Laura-Lemerveil-affiche-pavillon-Suzanne-Leclerc-scaled.jpg\" alt=\"Affiche \u00e0 l'accueil\" width=\"535\" height=\"301\" srcset=\"https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2024\/03\/Laura-Lemerveil-affiche-pavillon-Suzanne-Leclerc-scaled.jpg 2560w, https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2024\/03\/Laura-Lemerveil-affiche-pavillon-Suzanne-Leclerc-300x169.jpg 300w, https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2024\/03\/Laura-Lemerveil-affiche-pavillon-Suzanne-Leclerc-1024x576.jpg 1024w, https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2024\/03\/Laura-Lemerveil-affiche-pavillon-Suzanne-Leclerc-768x432.jpg 768w, https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2024\/03\/Laura-Lemerveil-affiche-pavillon-Suzanne-Leclerc-1536x864.jpg 1536w, https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2024\/03\/Laura-Lemerveil-affiche-pavillon-Suzanne-Leclerc-2048x1153.jpg 2048w\" sizes=\"auto, (max-width: 535px) 100vw, 535px\" \/>\n<p>&nbsp;<\/p>\n<p>Pr\u00e9sentation du ch\u00e8que<\/p>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-1094\" src=\"https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2024\/03\/Laura-Lemerveil-Remise-cheque-2024-scaled.jpg\" alt=\"\" width=\"539\" height=\"303\" srcset=\"https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2024\/03\/Laura-Lemerveil-Remise-cheque-2024-scaled.jpg 2560w, https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2024\/03\/Laura-Lemerveil-Remise-cheque-2024-300x169.jpg 300w, https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2024\/03\/Laura-Lemerveil-Remise-cheque-2024-1024x576.jpg 1024w, https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2024\/03\/Laura-Lemerveil-Remise-cheque-2024-768x432.jpg 768w, https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2024\/03\/Laura-Lemerveil-Remise-cheque-2024-1536x864.jpg 1536w, https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2024\/03\/Laura-Lemerveil-Remise-cheque-2024-2048x1153.jpg 2048w\" sizes=\"auto, (max-width: 539px) 100vw, 539px\" \/>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left;\">Photos de quelques enfants utilisant les lieux<\/p>\n<p style=\"text-align: left;\">P<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1096 alignleft\" src=\"https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2024\/03\/Laura-Lemerveil-photos-des-enfants-scaled.jpg\" alt=\"\" width=\"546\" height=\"307\" srcset=\"https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2024\/03\/Laura-Lemerveil-photos-des-enfants-scaled.jpg 2560w, https:\/\/heritageclub.ca\/kebec\/wp-content\/uploads\/sites\/13\/2024\/03\/Laura-Lemerveil-photos-des-enfants-300x169.jpg 300w\" sizes=\"auto, (max-width: 546px) 100vw, 546px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Suite \u00e0 une demande d\u2019appui financier, c\u2019est avec plaisir que le pr\u00e9sident Marc Jacob est all\u00e9 pr\u00e9senter un ch\u00e8que \u00a0de $500 \u00e0 Madame Martine Thibault, Directrice du d\u00e9veloppement philanthropique chez Laura L\u00e9merveil. La pr\u00e9sentation a eu lieu \u00e0 la Maison Famille Suzanne Leclerc le 13 mars dernier. Voici la raison d\u2019\u00eatre de cet organisme exceptionnel\u00a0:&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/heritageclub.ca\/kebec\/2024\/03\/16\/don-de-500-a-lorganisme-laura-lemerveil\/\" title=\"Read Don de $500 \u00e0 l&rsquo;organisme Laura L\u00e9merveil\">Lire la suite &raquo;<\/a><\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1099","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/heritageclub.ca\/kebec\/wp-json\/wp\/v2\/posts\/1099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/heritageclub.ca\/kebec\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/heritageclub.ca\/kebec\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/heritageclub.ca\/kebec\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/heritageclub.ca\/kebec\/wp-json\/wp\/v2\/comments?post=1099"}],"version-history":[{"count":6,"href":"https:\/\/heritageclub.ca\/kebec\/wp-json\/wp\/v2\/posts\/1099\/revisions"}],"predecessor-version":[{"id":1105,"href":"https:\/\/heritageclub.ca\/kebec\/wp-json\/wp\/v2\/posts\/1099\/revisions\/1105"}],"wp:attachment":[{"href":"https:\/\/heritageclub.ca\/kebec\/wp-json\/wp\/v2\/media?parent=1099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/heritageclub.ca\/kebec\/wp-json\/wp\/v2\/categories?post=1099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/heritageclub.ca\/kebec\/wp-json\/wp\/v2\/tags?post=1099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}